{"id":175,"count":1,"description":"","link":"https:\/\/daastan.com\/blog\/tag\/corona\/","name":"Corona","slug":"corona","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corona Archives - Daastan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daastan.com\/blog\/tag\/corona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corona Archives - Daastan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daastan.com\/blog\/tag\/corona\/\" \/>\n<meta property=\"og:site_name\" content=\"Daastan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mydaastan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/tag\\\/corona\\\/\",\"url\":\"https:\\\/\\\/daastan.com\\\/blog\\\/tag\\\/corona\\\/\",\"name\":\"Corona Archives - Daastan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/tag\\\/corona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/tag\\\/corona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/daastan.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/daastan.com\\\/blog\\\/\",\"name\":\"Daastan\",\"description\":\"Book Publishing Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daastan.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/#organization\",\"name\":\"Daastan\",\"url\":\"https:\\\/\\\/daastan.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daastan.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Home-page-Daastan-Qissa-Publishing-Pakistan-logo.jpeg\",\"contentUrl\":\"https:\\\/\\\/daastan.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Home-page-Daastan-Qissa-Publishing-Pakistan-logo.jpeg\",\"width\":600,\"height\":700,\"caption\":\"Daastan\"},\"image\":{\"@id\":\"https:\\\/\\\/daastan.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mydaastan\\\/\",\"https:\\\/\\\/x.com\\\/mydaastan\",\"https:\\\/\\\/www.instagram.com\\\/mydaastan\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/daastan\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVzRfguHxJvzznVGZG67PFQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corona Archives - Daastan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daastan.com\/blog\/tag\/corona\/","og_locale":"en_US","og_type":"article","og_title":"Corona Archives - Daastan","og_url":"https:\/\/daastan.com\/blog\/tag\/corona\/","og_site_name":"Daastan","twitter_card":"summary_large_image","twitter_site":"@mydaastan","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/daastan.com\/blog\/tag\/corona\/","url":"https:\/\/daastan.com\/blog\/tag\/corona\/","name":"Corona Archives - Daastan","isPartOf":{"@id":"https:\/\/daastan.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/daastan.com\/blog\/tag\/corona\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/daastan.com\/blog\/tag\/corona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/daastan.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Corona"}]},{"@type":"WebSite","@id":"https:\/\/daastan.com\/blog\/#website","url":"https:\/\/daastan.com\/blog\/","name":"Daastan","description":"Book Publishing Platform","publisher":{"@id":"https:\/\/daastan.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daastan.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/daastan.com\/blog\/#organization","name":"Daastan","url":"https:\/\/daastan.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/daastan.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/daastan.com\/blog\/wp-content\/uploads\/2019\/12\/Home-page-Daastan-Qissa-Publishing-Pakistan-logo.jpeg","contentUrl":"https:\/\/daastan.com\/blog\/wp-content\/uploads\/2019\/12\/Home-page-Daastan-Qissa-Publishing-Pakistan-logo.jpeg","width":600,"height":700,"caption":"Daastan"},"image":{"@id":"https:\/\/daastan.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mydaastan\/","https:\/\/x.com\/mydaastan","https:\/\/www.instagram.com\/mydaastan\/","https:\/\/www.linkedin.com\/company\/daastan","https:\/\/www.youtube.com\/channel\/UCVzRfguHxJvzznVGZG67PFQ"]}]}},"_links":{"self":[{"href":"https:\/\/daastan.com\/blog\/wp-json\/wp\/v2\/tags\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daastan.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/daastan.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/daastan.com\/blog\/wp-json\/wp\/v2\/posts?tags=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}